{"id":10797,"date":"2025-11-27T23:03:51","date_gmt":"2025-11-27T22:03:51","guid":{"rendered":"https:\/\/hugorodriguez.com\/escuela\/?page_id=10797"},"modified":"2026-01-03T20:42:46","modified_gmt":"2026-01-03T19:42:46","slug":"sony-camera-master-course-post-2020-edition","status":"publish","type":"page","link":"https:\/\/hugorodriguez.com\/escuela\/cursos\/sony-camera-master-course-post-2020-edition\/","title":{"rendered":"SONY Camera Master Course &#8211; Post-2020"},"content":{"rendered":"\n<figure class=\"wp-block-image aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"960\" height=\"540\" src=\"https:\/\/hugorodriguez.com\/escuela\/wp-content\/uploads\/2025\/11\/Videocurso-Master-CAM-SONY-II-01-660px.webp\" alt=\"\" class=\"wp-image-11073\" srcset=\"https:\/\/hugorodriguez.com\/escuela\/wp-content\/uploads\/2025\/11\/Videocurso-Master-CAM-SONY-II-01-660px.webp 960w, https:\/\/hugorodriguez.com\/escuela\/wp-content\/uploads\/2025\/11\/Videocurso-Master-CAM-SONY-II-01-660px-600x338.webp 600w, https:\/\/hugorodriguez.com\/escuela\/wp-content\/uploads\/2025\/11\/Videocurso-Master-CAM-SONY-II-01-660px-300x169.webp 300w, https:\/\/hugorodriguez.com\/escuela\/wp-content\/uploads\/2025\/11\/Videocurso-Master-CAM-SONY-II-01-660px-768x432.webp 768w\" sizes=\"auto, (max-width: 960px) 100vw, 960px\" \/><\/figure>\n\n\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>Ya llevas unos a\u00f1os con la fotograf\u00eda y tienes una SONY Alpha. Te consideras un usuario de nivel medio o avanzado, o eres un profesional. Tus fotos ya empiezan a estar muy bien, pero quieres seguir mejorando; el problema es que cuanto mayor es el nivel que tienes, m\u00e1s cuesta seguir subiendo, \u00bfverdad? Es l\u00f3gico, al principio se absorben conocimientos a mucha velocidad, pero poco a poco el ritmo se va normalizando. Te presento mi SONY Camera Master Course, probablemente el curso de manejo de c\u00e1mara m\u00e1s avanzado que vas a encontrar en todo Internet.<\/p>\n\n\n\n<p>Este Master Camera Course es el resultado de a\u00f1os de experiencia manejando todo tipo de c\u00e1maras y de haber testeado, analizado y publicado docenas de art\u00edculos en revistas de \u00e1mbito profesional como la -ya extinta- Casanova Professional.<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"500\" src=\"https:\/\/hugorodriguez.com\/escuela\/wp-content\/uploads\/2024\/05\/SONY-a7-R-S-alpha-600px-copia.webp\" alt=\"\" class=\"wp-image-5781\" style=\"object-fit:cover\" srcset=\"https:\/\/hugorodriguez.com\/escuela\/wp-content\/uploads\/2024\/05\/SONY-a7-R-S-alpha-600px-copia.webp 1200w, https:\/\/hugorodriguez.com\/escuela\/wp-content\/uploads\/2024\/05\/SONY-a7-R-S-alpha-600px-copia-600x250.webp 600w, https:\/\/hugorodriguez.com\/escuela\/wp-content\/uploads\/2024\/05\/SONY-a7-R-S-alpha-600px-copia-300x125.webp 300w, https:\/\/hugorodriguez.com\/escuela\/wp-content\/uploads\/2024\/05\/SONY-a7-R-S-alpha-600px-copia-1080x450.webp 1080w, https:\/\/hugorodriguez.com\/escuela\/wp-content\/uploads\/2024\/05\/SONY-a7-R-S-alpha-600px-copia-768x320.webp 768w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/><\/figure>\n\n\n\n<p>Este curso se desarolla con la colaboraci\u00f3n de  <img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"20\" class=\"wp-image-6560\" style=\"width: 150px;\" src=\"https:\/\/hugorodriguez.com\/escuela\/wp-content\/uploads\/2024\/06\/logo-casanovafoto-400px.png\" alt=\"\" srcset=\"https:\/\/hugorodriguez.com\/escuela\/wp-content\/uploads\/2024\/06\/logo-casanovafoto-400px.png 400w, https:\/\/hugorodriguez.com\/escuela\/wp-content\/uploads\/2024\/06\/logo-casanovafoto-400px-300x41.png 300w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/p>\n\n\n\n<p>Si quieres encontrar todo tipo de productos SONY, con un asesoramiento experto, no lo dudes: <a href=\"http:\/\/www.casanovafoto.com\">haz clic <\/a><a href=\"https:\/\/www.casanovafoto.com\/fotografia\/objetivos\/mirrorless-full-frame\/sony\" target=\"_blank\" rel=\"noreferrer noopener\">aqui<\/a><\/p>\n\n\n\n<p>Este curso est\u00e1 dirigido a todos aquellos aficionados de nivel medio, alto o profesionales que quieren descubrir c\u00f3mo exprimir al m\u00e1ximo su c\u00e1mara para poder obtener tanto mejores im\u00e1genes, como para obtenerlas con menos esfuerzo.<\/p>\n\n\n\n<p>Pero tambi\u00e9n a aqu\u00e9llos que acaban de cambiar de marca de c\u00e1mara y se sienten perdidos con todas las funciones y men\u00fas de su nueva c\u00e1mara SONY. Con este curso te familizar\u00e1s con tu nueva SONY en tiempo r\u00e9cord.<\/p>\n\n\n\n<p>Este curso es para <strong>c\u00e1maras SONY de la serie Alpha fabricadas a partir de 2020, desde la a7 IV<\/strong> (inclu\u00edda).<br><br>\u00bfTienes una c\u00e1mara SONY anterior a 2020 (con el antiguo sistema de men\u00fas) y buscas un curso para ella? Pues tambien tienes la edici\u00f3n pre-2020:<\/p>\n\n\n\n<div class=\"wp-block-buttons is-content-justification-center is-layout-flex wp-container-core-buttons-is-layout-1 wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/hugorodriguez.com\/escuela\/cursos\/master-camera-course-sony-pre-2020-edition\/\">ver la edici\u00f3n pre-2020<\/a><\/div>\n<\/div>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity is-style-dots\" style=\"margin-top:var(--wp--preset--spacing--60);margin-bottom:var(--wp--preset--spacing--60)\"\/>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-f73bbf0c default uagb-is-root-container\">\n<div class=\"wp-block-uagb-container uagb-block-f784b5a5\">\n<p class=\"has-text-align-center\" style=\"font-size:24px\">Compra el curso por s\u00f3lo <s>74,95\u20ac<\/s> <strong>34,95\u20ac<\/strong><\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-470714d1\"><div class=\"learndash-wrapper learndash-wrap learndash-shortcode-wrap\"><a class=\"btn-join learndash-button-closed\" id=\"btn-join\" href=\"https:\/\/hugorodriguez.com\/escuela\/finalizar-compra\/?add-to-cart=11057\">Apuntarme<\/a><\/div><\/div>\n<\/div>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity is-style-dots\" style=\"margin-top:var(--wp--preset--spacing--60);margin-bottom:var(--wp--preset--spacing--60)\"\/>\n\n\n\n<h2 class=\"wp-block-heading has-text-align-center\" style=\"font-size:28px\">\u00bfQUE APRENDER\u00c1S?<\/h2>\n\n\n\n<p>Muy sencillo: descubrir el uso \u00f3ptimo de todas aquellas funciones verdaderamente \u00fatiles que te ofreza tu c\u00e1mara. No s\u00f3lo eso, tambi\u00e9n aprender cu\u00e1l es la mejor configuraci\u00f3n tanto a nivel general, como espec\u00edfico para diferentes tipos de fotografia. Desde un desglose pormenorizado de todos los modos y ajustes del AF, pasando por configurar a tu medida el Live View (y sus pantallas e iconos), como mejorar exponencialmente tu forma de medir y exponer tus fotos y multitud de aspectos m\u00e1s.<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1080\" height=\"402\" src=\"https:\/\/hugorodriguez.com\/escuela\/wp-content\/uploads\/2024\/05\/SONY-a7RIV-fondo-negro-1200px-1080x402.webp\" alt=\"\" class=\"wp-image-5857\" style=\"object-fit:cover\" srcset=\"https:\/\/hugorodriguez.com\/escuela\/wp-content\/uploads\/2024\/05\/SONY-a7RIV-fondo-negro-1200px-1080x402.webp 1080w, https:\/\/hugorodriguez.com\/escuela\/wp-content\/uploads\/2024\/05\/SONY-a7RIV-fondo-negro-1200px-600x224.webp 600w, https:\/\/hugorodriguez.com\/escuela\/wp-content\/uploads\/2024\/05\/SONY-a7RIV-fondo-negro-1200px-300x112.webp 300w, https:\/\/hugorodriguez.com\/escuela\/wp-content\/uploads\/2024\/05\/SONY-a7RIV-fondo-negro-1200px-768x286.webp 768w, https:\/\/hugorodriguez.com\/escuela\/wp-content\/uploads\/2024\/05\/SONY-a7RIV-fondo-negro-1200px.webp 1200w\" sizes=\"auto, (max-width: 1080px) 100vw, 1080px\" \/><\/figure>\n\n\n\n<p>Descubriras por ejemplo, c\u00f3mo configurarla exactamente para que el histograma que usas para exponer (y si aun no lo usas, aprender\u00e1s por qu\u00e9 debes) se parezcan much\u00edsimo m\u00e1s al RAW. O por qu\u00e9 no deber\u00edas usar unas sensibilidades ISO y otras s\u00ed (el comportamiento ISO invariante de algunas c\u00e1maras). O c\u00f3mo optimizar la c\u00e1mara al m\u00e1ximo tanto para fotograf\u00eda de paisaje\/bodeg\u00f3n como para instant\u00e1neas imprevistas o fotograf\u00eda de acci\u00f3n.<\/p>\n\n\n\n<p>En definitiva, conoceras tu c\u00e1mara tan a fondo en lo verdaderamente esencial que te sentiras totalmente conectado a tu c\u00e1mara para que sea una extensi\u00f3n de tu mente y puedas sacar mejores fotos, con menos esfuerzo y en menor tiempo.<\/p>\n\n\n\n<p>El curso est\u00e1 realizado con mi \u00faltimo sistema de producci\u00f3n audiovisual profesional, de calidad televisiva, y encontrar\u00e1s que he cuidado hasta el \u00faltimo detalle.<\/p>\n\n\n\n<div class=\"wp-block-uagb-image aligncenter uagb-block-93f4ac15 wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-center\"><figure class=\"wp-block-uagb-image__figure\"><img decoding=\"async\" srcset=\"https:\/\/hugorodriguez.com\/escuela\/wp-content\/uploads\/2024\/08\/Hugo-explicando-en-el-curso_resize.jpg ,https:\/\/hugorodriguez.com\/escuela\/wp-content\/uploads\/2024\/08\/Hugo-explicando-en-el-curso_resize.jpg 780w, https:\/\/hugorodriguez.com\/escuela\/wp-content\/uploads\/2024\/08\/Hugo-explicando-en-el-curso_resize.jpg 360w\" sizes=\"auto, (max-width: 480px) 150px\" src=\"https:\/\/hugorodriguez.com\/escuela\/wp-content\/uploads\/2024\/08\/Hugo-explicando-en-el-curso_resize.jpg\" alt=\"\" class=\"uag-image-7227\" width=\"600\" height=\"338\" title=\"\" loading=\"lazy\" role=\"img\"\/><\/figure><\/div>\n\n\n\n<p>Cada vez que hay que explicar c\u00f3mo se utiliza una funci\u00f3n en particular, ver\u00e1s la c\u00e1mara delante de un bodeg\u00f3n de especialmente preparado (no simplemente una captura de los men\u00fas via HDMI), con mis manos manejandola mientras te explico de voz paso a paso. M\u00e1s f\u00e1cil, imposible.<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"338\" src=\"https:\/\/hugorodriguez.com\/escuela\/wp-content\/uploads\/2025\/12\/Captura-manejando-SONY-a7-IV_resize.webp\" alt=\"\" class=\"wp-image-11077\" srcset=\"https:\/\/hugorodriguez.com\/escuela\/wp-content\/uploads\/2025\/12\/Captura-manejando-SONY-a7-IV_resize.webp 600w, https:\/\/hugorodriguez.com\/escuela\/wp-content\/uploads\/2025\/12\/Captura-manejando-SONY-a7-IV_resize-300x169.webp 300w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/figure>\n\n\n\n<p>Incluso el moir\u00e9 que aparece al filmar la pantalla de la c\u00e1mara y \u00a1hasta los reflejos de la pantalla de la c\u00e1mara! se han tenido en cuenta&#8230;<\/p>\n\n\n\n<p>Cuando hay que explicar algo de teor\u00eda se usan presentaciones de calidad profesional y gran limpieza en las que la informaci\u00f3n est\u00e1 presentada de forma elegante y de f\u00e1cil lectura.<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter wp-image-28552\"><img decoding=\"async\" src=\"https:\/\/www.hugorodriguez.com\/blog\/wp-content\/uploads\/2024\/05\/Hugo-explicando-Powerpoint.jpg\" alt=\"\" class=\"wp-image-28552\" style=\"object-fit:cover\"\/><\/figure>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity is-style-dots\" style=\"margin-top:var(--wp--preset--spacing--60);margin-bottom:var(--wp--preset--spacing--60)\"\/>\n\n\n\n<h2 class=\"wp-block-heading has-text-align-center\" style=\"font-size:28px\">\u00bfQU\u00c9 OPINAN NUESTROS ALUMNOS?<\/h2>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-64de92d0 alignwide uagb-is-root-container\">\n<div class=\"wp-block-uagb-testimonial uagb-slick-carousel uagb-tm__arrow-outside uagb-block-16992d44\"><div class=\"is-carousel uagb-tm__columns-3 uagb-tm__items\"><div class=\"uagb-testimonial__wrap  uagb-tm__imgicon-style-circle uagb-tm__image-position-bottom uagb-tm__bg-type-none \"><div class=\"uagb-tm__content\"><div class=\"uagb-tm__overlay\"><\/div><div class=\"uagb-tm__text-wrap\"><div class=\"uagb-tm__desc\">Este curso me ha permitido, adem\u00e1s de conocer en profundidad mi c\u00e1mara, replantearme como ajustarla para las diferentes fases por la que pasa la realizaci\u00f3n de una fotograf\u00eda, con un planteamiento novedoso e imaginativo. Curso imprescindible para todos y en particular para esp\u00edritus perfeccionistas.<\/div><div class=\"uagb-tm__meta-inner\"><div class=\"uagb-tm__image-content\"><div class=\"uagb-tm__image\"><img decoding=\"async\" class=\"uagb-tm-img-src\" src=\"https:\/\/hugorodriguez.com\/escuela\/wp-content\/uploads\/2024\/05\/Sergio-Royo_resize.webp\" alt=\"\" width=\"60\" height=\"60\" loading=\"lazy\"\/><\/div><\/div><div class=\"uagb-testimonial-details\"><span class=\"uagb-tm__author-name\">Sergio Royo<\/span><span class=\"uagb-tm__company\">SONY Camera\u00a0Master Course<\/span><\/div><\/div><\/div><\/div><\/div><div class=\"uagb-testimonial__wrap  uagb-tm__imgicon-style-circle uagb-tm__image-position-bottom uagb-tm__bg-type-none \"><div class=\"uagb-tm__content\"><div class=\"uagb-tm__overlay\"><\/div><div class=\"uagb-tm__text-wrap\"><div class=\"uagb-tm__desc\">Digo promete mucho, porque a\u00fan estoy en los primeros cap\u00edtulos, y a pesar de llevar m\u00e1s de 30 a\u00f1os haciendo fotos, ya he podido saber, por fin, la manera de graduar correctamente el visor \u00f3ptico, algo esencial, pero que nunca nadie me hab\u00eda explicado. Llevo viendo muchos videos de Hugo en You Tube, y el curso es tan ameno y entendedor como nos tiene acostumbrados en todos ellos. Es evidente que son muchas horas de dedicaci\u00f3n, pero que agradecemos, sin duda, todos los amantes de la fotograf\u00eda.<\/div><div class=\"uagb-tm__meta-inner\"><div class=\"uagb-tm__image-content\"><div class=\"uagb-tm__image\"><img decoding=\"async\" class=\"uagb-tm-img-src\" src=\"https:\/\/hugorodriguez.com\/escuela\/wp-content\/uploads\/2024\/05\/Carles-Costa_resize.webp\" alt=\"\" width=\"60\" height=\"60\" loading=\"lazy\"\/><\/div><\/div><div class=\"uagb-testimonial-details\"><span class=\"uagb-tm__author-name\">Carles Costa<\/span><span class=\"uagb-tm__company\">SONY Camera\u00a0Master Course<\/span><\/div><\/div><\/div><\/div><\/div><div class=\"uagb-testimonial__wrap  uagb-tm__imgicon-style-circle uagb-tm__image-position-bottom uagb-tm__bg-type-none \"><div class=\"uagb-tm__content\"><div class=\"uagb-tm__overlay\"><\/div><div class=\"uagb-tm__text-wrap\"><div class=\"uagb-tm__desc\">Me ha \u201cenganchado\u201d completamente el curso: no sab\u00eda el porqu\u00e9 de las distintas configuraciones para mi c\u00e1mara SONY bajadas de Youtube, las copiaba y ya est\u00e1. En este curso, Hugo te explica como funcionan cada uno de los los par\u00e1metros de configuraci\u00f3n de una forma sencilla y asimilable, ahora ya se entienden el porqu\u00e9 de esas configuraciones y est\u00e1s a mucho mayor nivel que antes. Muchas gracias por este curso.<\/div><div class=\"uagb-tm__meta-inner\"><div class=\"uagb-tm__image-content\"><div class=\"uagb-tm__image\"><img decoding=\"async\" class=\"uagb-tm-img-src\" src=\"https:\/\/hugorodriguez.com\/escuela\/wp-content\/uploads\/2024\/02\/Usuario-generico-100x100-1.webp\" alt=\"\" width=\"60\" height=\"60\" loading=\"lazy\"\/><\/div><\/div><div class=\"uagb-testimonial-details\"><span class=\"uagb-tm__author-name\">Hantonio<\/span><span class=\"uagb-tm__company\">SONY Camera\u00a0Master Course<\/span><\/div><\/div><\/div><\/div><\/div><div class=\"uagb-testimonial__wrap  uagb-tm__imgicon-style-circle uagb-tm__image-position-bottom uagb-tm__bg-type-none \"><div class=\"uagb-tm__content\"><div class=\"uagb-tm__overlay\"><\/div><div class=\"uagb-tm__text-wrap\"><div class=\"uagb-tm__desc\">Un curso genial, de los que sales con la sensaci\u00f3n de haber aprendido de verdad como funciona la c\u00e1mara. Me ha encantado la manera sencilla que tienes Hugo de explicar cosas bastante t\u00e9cnicas, con ejemplos reales y con su correspondiente proceso de configuraci\u00f3n en c\u00e1mara. Realmente he notado un cambio bestia en las fotografias que hago, pudiendo mejorar la exposici\u00f3n, nitidez, colores, etc. gracias a los trucos y recomendaciones del curso. Para mi, un antes y un despu\u00e9s ha significado este curso. Imprescindible es su mejor definici\u00f3n.<\/div><div class=\"uagb-tm__meta-inner\"><div class=\"uagb-tm__image-content\"><div class=\"uagb-tm__image\"><img decoding=\"async\" class=\"uagb-tm-img-src\" src=\"https:\/\/hugorodriguez.com\/escuela\/wp-content\/uploads\/2024\/02\/Usuario-generico-100x100-1.webp\" alt=\"Icono Avatar\" width=\"60\" height=\"60\" loading=\"lazy\"\/><\/div><\/div><div class=\"uagb-testimonial-details\"><span class=\"uagb-tm__author-name\">We.Are.Colours<\/span><span class=\"uagb-tm__company\">SONY Camera\u00a0Master Course<\/span><\/div><\/div><\/div><\/div><\/div><div class=\"uagb-testimonial__wrap  uagb-tm__imgicon-style-circle uagb-tm__image-position-bottom uagb-tm__bg-type-none \"><div class=\"uagb-tm__content\"><div class=\"uagb-tm__overlay\"><\/div><div class=\"uagb-tm__text-wrap\"><div class=\"uagb-tm__desc\">Quiero decir que a pesar de que llevo m\u00e1s de dos a\u00f1os con mi c\u00e1mara sony, siempre se puede aprender algo nuevo, es un buen curso, bien estructurado y muy din\u00e1mico. Como decimos en Chile \u00a1Gracias Profe!<\/div><div class=\"uagb-tm__meta-inner\"><div class=\"uagb-tm__image-content\"><div class=\"uagb-tm__image\"><img decoding=\"async\" class=\"uagb-tm-img-src\" src=\"https:\/\/hugorodriguez.com\/escuela\/wp-content\/uploads\/2024\/02\/Usuario-generico-100x100-1.webp\" alt=\"Icono Avatar\" width=\"60\" height=\"60\" loading=\"lazy\"\/><\/div><\/div><div class=\"uagb-testimonial-details\"><span class=\"uagb-tm__author-name\">Minoltero<\/span><span class=\"uagb-tm__company\">SONY Camera\u00a0Master Course<\/span><\/div><\/div><\/div><\/div><\/div><div class=\"uagb-testimonial__wrap  uagb-tm__imgicon-style-circle uagb-tm__image-position-bottom uagb-tm__bg-type-none \"><div class=\"uagb-tm__content\"><div class=\"uagb-tm__overlay\"><\/div><div class=\"uagb-tm__text-wrap\"><div class=\"uagb-tm__desc\">Muy contento con este curso que es muy completo, muchas gracias maestro, eh aprendido mucho a como manejar y conocer mas mi c\u00e1mara y configurarla. saludos desde Charlotte Carolina del Norte.<\/div><div class=\"uagb-tm__meta-inner\"><div class=\"uagb-tm__image-content\"><div class=\"uagb-tm__image\"><img decoding=\"async\" class=\"uagb-tm-img-src\" src=\"https:\/\/hugorodriguez.com\/escuela\/wp-content\/uploads\/2024\/02\/Usuario-generico-100x100-1.webp\" alt=\"Icono Avatar\" width=\"60\" height=\"60\" loading=\"lazy\"\/><\/div><\/div><div class=\"uagb-testimonial-details\"><span class=\"uagb-tm__author-name\">Isma<\/span><span class=\"uagb-tm__company\">SONY Camera\u00a0Master Course<\/span><\/div><\/div><\/div><\/div><\/div><\/div><\/div>\n<\/div>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity is-style-dots\" style=\"margin-top:var(--wp--preset--spacing--60);margin-bottom:var(--wp--preset--spacing--60)\"\/>\n\n\n\n<h2 class=\"wp-block-heading has-text-align-center\" style=\"font-size:28px\">\u00bfQU\u00c9 OBTIENES CON ESTE CURSO?<\/h2>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-1 wp-block-columns-is-layout-flex\" style=\"padding-top:20px;padding-bottom:20px\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<div class=\"wp-block-uagb-info-box uagb-block-452f0397 uagb-infobox__content-wrap  uagb-infobox-icon-left uagb-infobox-left uagb-infobox-stacked-tablet uagb-infobox-image-valign-top\"><div class=\"uagb-ifb-icon-wrap\"><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\"><path d=\"M194.6 32H317.4C338.1 32 356.4 45.22 362.9 64.82L373.3 96H448C483.3 96 512 124.7 512 160V416C512 451.3 483.3 480 448 480H64C28.65 480 0 451.3 0 416V160C0 124.7 28.65 96 64 96H138.7L149.1 64.82C155.6 45.22 173.9 32 194.6 32H194.6zM256 384C309 384 352 341 352 288C352 234.1 309 192 256 192C202.1 192 160 234.1 160 288C160 341 202.1 384 256 384z\"><\/path><\/svg><\/div><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-title-wrap\"><h4 class=\"uagb-ifb-title\">PARA TU SONY ALPHA*<\/h4><\/div><p class=\"uagb-ifb-desc\">Todas las explicaciones est\u00e1n hechas con c\u00e1maras SONY y todas las funciones mostradas en los men\u00fas tambien.<br>*: para modelos desde la a7IV.<\/p><\/div><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<div class=\"wp-block-uagb-info-box uagb-block-ca4730f2 uagb-infobox__content-wrap  uagb-infobox-icon-left uagb-infobox-left uagb-infobox-stacked-mobile uagb-infobox-image-valign-top\"><div class=\"uagb-ifb-icon-wrap\"><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\"><path d=\"M480 352h-133.5l-45.25 45.25C289.2 409.3 273.1 416 256 416s-33.16-6.656-45.25-18.75L165.5 352H32c-17.67 0-32 14.33-32 32v96c0 17.67 14.33 32 32 32h448c17.67 0 32-14.33 32-32v-96C512 366.3 497.7 352 480 352zM432 456c-13.2 0-24-10.8-24-24c0-13.2 10.8-24 24-24s24 10.8 24 24C456 445.2 445.2 456 432 456zM233.4 374.6C239.6 380.9 247.8 384 256 384s16.38-3.125 22.62-9.375l128-128c12.49-12.5 12.49-32.75 0-45.25c-12.5-12.5-32.76-12.5-45.25 0L288 274.8V32c0-17.67-14.33-32-32-32C238.3 0 224 14.33 224 32v242.8L150.6 201.4c-12.49-12.5-32.75-12.5-45.25 0c-12.49 12.5-12.49 32.75 0 45.25L233.4 374.6z\"><\/path><\/svg><\/div><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-title-wrap\"><h4 class=\"uagb-ifb-title\">MATERIALES PARA DESCARGA<\/h4><\/div><p class=\"uagb-ifb-desc\">Podr\u00e1s descargar las configuraciones de c\u00e1mara y las im\u00e1genes mostradas para experimentar.<\/p><\/div><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<div class=\"wp-block-uagb-info-box uagb-block-39ba811a uagb-infobox__content-wrap  uagb-infobox-icon-left uagb-infobox-left uagb-infobox-stacked-mobile uagb-infobox-image-valign-top\"><div class=\"uagb-ifb-icon-wrap\"><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\"><path d=\"M256 53.46L300.1 7.261C307 1.034 315.1-1.431 324.4 .8185C332.8 3.068 339.3 9.679 341.4 18.1L357.3 80.6L419.3 63.07C427.7 60.71 436.7 63.05 442.8 69.19C448.1 75.34 451.3 84.33 448.9 92.69L431.4 154.7L493.9 170.6C502.3 172.7 508.9 179.2 511.2 187.6C513.4 196 510.1 204.1 504.7 211L458.5 256L504.7 300.1C510.1 307 513.4 315.1 511.2 324.4C508.9 332.8 502.3 339.3 493.9 341.4L431.4 357.3L448.9 419.3C451.3 427.7 448.1 436.7 442.8 442.8C436.7 448.1 427.7 451.3 419.3 448.9L357.3 431.4L341.4 493.9C339.3 502.3 332.8 508.9 324.4 511.2C315.1 513.4 307 510.1 300.1 504.7L256 458.5L211 504.7C204.1 510.1 196 513.4 187.6 511.2C179.2 508.9 172.7 502.3 170.6 493.9L154.7 431.4L92.69 448.9C84.33 451.3 75.34 448.1 69.19 442.8C63.05 436.7 60.71 427.7 63.07 419.3L80.6 357.3L18.1 341.4C9.679 339.3 3.068 332.8 .8186 324.4C-1.431 315.1 1.034 307 7.261 300.1L53.46 256L7.261 211C1.034 204.1-1.431 196 .8186 187.6C3.068 179.2 9.679 172.7 18.1 170.6L80.6 154.7L63.07 92.69C60.71 84.33 63.05 75.34 69.19 69.19C75.34 63.05 84.33 60.71 92.69 63.07L154.7 80.6L170.6 18.1C172.7 9.679 179.2 3.068 187.6 .8185C196-1.431 204.1 1.034 211 7.261L256 53.46z\"><\/path><\/svg><\/div><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-title-wrap\"><h4 class=\"uagb-ifb-title\">CERTIFICADO<\/h4><\/div><p class=\"uagb-ifb-desc\">Al terminar recibir\u00e1s un elegante certificado. que podr\u00e1s imprimir con alta calidad en A4 y a 300ppi!<\/p><\/div><\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-2 wp-block-columns-is-layout-flex\" style=\"padding-top:20px;padding-bottom:20px\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<div class=\"wp-block-uagb-info-box uagb-block-afb2dcb6 uagb-infobox__content-wrap  uagb-infobox-icon-left uagb-infobox-left uagb-infobox-stacked-tablet uagb-infobox-image-valign-top\"><div class=\"uagb-ifb-icon-wrap\"><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\"><path d=\"M156.6 384.9L125.7 353.1C117.2 345.5 114.2 333.1 117.1 321.8C120.1 312.9 124.1 301.3 129.8 288H24C15.38 288 7.414 283.4 3.146 275.9C-1.123 268.4-1.042 259.2 3.357 251.8L55.83 163.3C68.79 141.4 92.33 127.1 117.8 127.1H200C202.4 124 204.8 120.3 207.2 116.7C289.1-4.07 411.1-8.142 483.9 5.275C495.6 7.414 504.6 16.43 506.7 28.06C520.1 100.9 516.1 222.9 395.3 304.8C391.8 307.2 387.1 309.6 384 311.1V394.2C384 419.7 370.6 443.2 348.7 456.2L260.2 508.6C252.8 513 243.6 513.1 236.1 508.9C228.6 504.6 224 496.6 224 488V380.8C209.9 385.6 197.6 389.7 188.3 392.7C177.1 396.3 164.9 393.2 156.6 384.9V384.9zM384 167.1C406.1 167.1 424 150.1 424 127.1C424 105.9 406.1 87.1 384 87.1C361.9 87.1 344 105.9 344 127.1C344 150.1 361.9 167.1 384 167.1z\"><\/path><\/svg><\/div><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-title-wrap\"><h4 class=\"uagb-ifb-title\">SUPER-INTENSIVO<\/h4><\/div><p class=\"uagb-ifb-desc\">Pasa de nivel medio a Pro en tiempo record, pero de forma progresiva. Y amena.<\/p><\/div><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<div class=\"wp-block-uagb-info-box uagb-block-16891496 uagb-infobox__content-wrap  uagb-infobox-icon-left uagb-infobox-left uagb-infobox-stacked-tablet uagb-infobox-image-valign-top\"><div class=\"uagb-ifb-icon-wrap\"><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\"><path d=\"M512 256C512 397.4 397.4 512 256 512C114.6 512 0 397.4 0 256C0 114.6 114.6 0 256 0C397.4 0 512 114.6 512 256zM176 168V344C176 352.7 180.7 360.7 188.3 364.9C195.8 369.2 205.1 369 212.5 364.5L356.5 276.5C363.6 272.1 368 264.4 368 256C368 247.6 363.6 239.9 356.5 235.5L212.5 147.5C205.1 142.1 195.8 142.8 188.3 147.1C180.7 151.3 176 159.3 176 168V168z\"><\/path><\/svg><\/div><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-title-wrap\"><h4 class=\"uagb-ifb-title\">CAP\u00cdTULOS CORTOS<\/h4><\/div><p class=\"uagb-ifb-desc\">Para que sea m\u00e1s facil de ver&#8230; y retomar en cualquier momento. Incluso estando fuera de casa.<\/p><\/div><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<div class=\"wp-block-uagb-info-box uagb-block-330032cc uagb-infobox__content-wrap  uagb-infobox-icon-left uagb-infobox-left uagb-infobox-stacked-tablet uagb-infobox-image-valign-top\"><div class=\"uagb-ifb-icon-wrap\"><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 576 512\"><path d=\"M269.4 5.961C280.5-1.987 295.5-1.987 306.6 5.961L530.6 165.1C538 171.2 542.8 179.4 543.8 188.5L575.8 476.5C576.8 485.5 573.9 494.6 567.8 501.3C561.8 508.1 553.1 512 544 512H416L288 288V512H32C22.9 512 14.23 508.1 8.156 501.3C2.086 494.6-.8093 485.5 .1958 476.5L32.2 188.5C33.2 179.4 38 171.2 45.4 165.1L269.4 5.961z\"><\/path><\/svg><\/div><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-title-wrap\"><h4 class=\"uagb-ifb-title\">EN CUALQUIER LUGAR<\/h4><\/div><p class=\"uagb-ifb-desc\">No hace falta que te prepares como si fueras a asistir a una clase; puedes verlo en cualquier momento y lugar.<\/p><\/div><\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-3 wp-block-columns-is-layout-flex\" style=\"padding-top:20px;padding-bottom:20px\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<div class=\"wp-block-uagb-info-box uagb-block-825fe638 uagb-infobox__content-wrap  uagb-infobox-icon-left uagb-infobox-left uagb-infobox-stacked-tablet uagb-infobox-image-valign-top\"><div class=\"uagb-ifb-icon-wrap\"><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\"><path d=\"M464 16c-17.67 0-32 14.31-32 32v74.09C392.1 66.52 327.4 32 256 32C161.5 32 78.59 92.34 49.58 182.2c-5.438 16.81 3.797 34.88 20.61 40.28c16.89 5.5 34.88-3.812 40.3-20.59C130.9 138.5 189.4 96 256 96c50.5 0 96.26 24.55 124.4 64H336c-17.67 0-32 14.31-32 32s14.33 32 32 32h128c17.67 0 32-14.31 32-32V48C496 30.31 481.7 16 464 16zM441.8 289.6c-16.92-5.438-34.88 3.812-40.3 20.59C381.1 373.5 322.6 416 256 416c-50.5 0-96.25-24.55-124.4-64H176c17.67 0 32-14.31 32-32s-14.33-32-32-32h-128c-17.67 0-32 14.31-32 32v144c0 17.69 14.33 32 32 32s32-14.31 32-32v-74.09C119.9 445.5 184.6 480 255.1 480c94.45 0 177.4-60.34 206.4-150.2C467.9 313 458.6 294.1 441.8 289.6z\"><\/path><\/svg><\/div><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-title-wrap\"><h4 class=\"uagb-ifb-title\">CURSO ACTUALIZADO<\/h4><\/div><p class=\"uagb-ifb-desc\">Si las nuevas c\u00e1maras traen nuevas funciones, ir\u00e9 actualizando\/a\u00f1adiendo cap\u00edtulos al curso para que no te pierdas nada.<\/p><\/div><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<div class=\"wp-block-uagb-info-box uagb-block-b0b01a9f uagb-infobox__content-wrap  uagb-infobox-icon-left uagb-infobox-left uagb-infobox-stacked-tablet uagb-infobox-image-valign-top\"><div class=\"uagb-ifb-icon-wrap\"><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 640 512\"><path d=\"M535 7.03C544.4-2.343 559.6-2.343 568.1 7.029L632.1 71.02C637.5 75.52 640 81.63 640 87.99C640 94.36 637.5 100.5 632.1 104.1L568.1 168.1C559.6 178.3 544.4 178.3 535 168.1C525.7 159.6 525.7 144.4 535 135L558.1 111.1L384 111.1C370.7 111.1 360 101.2 360 87.99C360 74.74 370.7 63.99 384 63.99L558.1 63.1L535 40.97C525.7 31.6 525.7 16.4 535 7.03V7.03zM104.1 376.1L81.94 400L255.1 399.1C269.3 399.1 279.1 410.7 279.1 423.1C279.1 437.2 269.3 447.1 255.1 447.1L81.95 448L104.1 471C114.3 480.4 114.3 495.6 104.1 504.1C95.6 514.3 80.4 514.3 71.03 504.1L7.029 440.1C2.528 436.5-.0003 430.4 0 423.1C0 417.6 2.529 411.5 7.03 407L71.03 343C80.4 333.7 95.6 333.7 104.1 343C114.3 352.4 114.3 367.6 104.1 376.1H104.1zM95.1 64H337.9C334.1 71.18 332 79.34 332 87.1C332 116.7 355.3 139.1 384 139.1L481.1 139.1C484.4 157.5 494.9 172.5 509.4 181.9C511.1 184.3 513.1 186.6 515.2 188.8C535.5 209.1 568.5 209.1 588.8 188.8L608 169.5V384C608 419.3 579.3 448 544 448H302.1C305.9 440.8 307.1 432.7 307.1 423.1C307.1 395.3 284.7 371.1 255.1 371.1L158.9 372C155.5 354.5 145.1 339.5 130.6 330.1C128.9 327.7 126.9 325.4 124.8 323.2C104.5 302.9 71.54 302.9 51.23 323.2L31.1 342.5V128C31.1 92.65 60.65 64 95.1 64V64zM95.1 192C131.3 192 159.1 163.3 159.1 128H95.1V192zM544 384V320C508.7 320 480 348.7 480 384H544zM319.1 352C373 352 416 309 416 256C416 202.1 373 160 319.1 160C266.1 160 223.1 202.1 223.1 256C223.1 309 266.1 352 319.1 352z\"><\/path><\/svg><\/div><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-title-wrap\"><h4 class=\"uagb-ifb-title\">FUTUROS DESCUENTOS<\/h4><\/div><p class=\"uagb-ifb-desc\">Si sale una nueva edici\u00f3n del curso, podr\u00e1s ahorrarte una parte importante del coste del nuevo porque los cap\u00edtulos compartidos no los pagas.<\/p><\/div><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<div class=\"wp-block-uagb-info-box uagb-block-fff2c5e7 uagb-infobox__content-wrap  uagb-infobox-icon-left uagb-infobox-left uagb-infobox-stacked-tablet uagb-infobox-image-valign-top\"><div class=\"uagb-ifb-icon-wrap\"><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\"><path d=\"M512 256C512 397.4 397.4 512 256 512C114.6 512 0 397.4 0 256C0 114.6 114.6 0 256 0C397.4 0 512 114.6 512 256zM266.3 48.25L232.5 73.6C227.2 77.63 224 83.95 224 90.67V99.72C224 106.5 229.5 112 236.3 112C238.7 112 241.1 111.3 243.1 109.9L284.9 82.06C286.9 80.72 289.3 80 291.7 80H292.7C298.9 80 304 85.07 304 91.31C304 94.31 302.8 97.19 300.7 99.31L280.8 119.2C275 124.1 267.9 129.4 260.2 131.9L233.6 140.8C227.9 142.7 224 148.1 224 154.2C224 157.9 222.5 161.5 219.9 164.1L201.9 182.1C195.6 188.4 192 197.1 192 206.1V210.3C192 226.7 205.6 240 221.9 240C232.9 240 243.1 233.8 248 224L252 215.9C254.5 211.1 259.4 208 264.8 208C269.4 208 273.6 210.1 276.3 213.7L292.6 235.5C294.7 238.3 298.1 240 301.7 240C310.1 240 315.6 231.1 311.8 223.6L310.7 221.3C307.1 214.3 310.7 205.8 318.1 203.3L339.3 196.2C346.9 193.7 352 186.6 352 178.6C352 168.3 360.3 160 370.6 160H400C408.8 160 416 167.2 416 176C416 184.8 408.8 192 400 192H379.3C372.1 192 365.1 194.9 360 200L355.3 204.7C353.2 206.8 352 209.7 352 212.7C352 218.9 357.1 224 363.3 224H374.6C380.6 224 386.4 226.4 390.6 230.6L397.2 237.2C398.1 238.1 400 241.4 400 244C400 246.6 398.1 249 397.2 250.8L389.7 258.3C386 261.1 384 266.9 384 272C384 277.1 386 282 389.7 285.7L408 304C418.2 314.2 432.1 320 446.6 320H453.1C460.5 299.8 464 278.3 464 256C464 144.6 376.4 53.64 266.3 48.25V48.25zM438.4 356.1C434.7 353.5 430.2 352 425.4 352C419.4 352 413.6 349.6 409.4 345.4L395.1 331.1C388.3 324.3 377.9 320 367.1 320C357.4 320 347.9 316.5 340.5 310.2L313.1 287.4C302.4 277.5 287.6 271.1 272.3 271.1H251.4C238.7 271.1 226.4 275.7 215.9 282.7L188.5 301C170.7 312.9 160 332.9 160 354.3V357.5C160 374.5 166.7 390.7 178.7 402.7L194.7 418.7C203.2 427.2 214.7 432 226.7 432H248C261.3 432 272 442.7 272 456C272 458.5 272.4 461 273.1 463.3C344.5 457.5 405.6 415.7 438.4 356.1L438.4 356.1zM164.7 100.7L132.7 132.7C126.4 138.9 126.4 149.1 132.7 155.3C138.9 161.6 149.1 161.6 155.3 155.3L187.3 123.3C193.6 117.1 193.6 106.9 187.3 100.7C181.1 94.44 170.9 94.44 164.7 100.7V100.7z\"><\/path><\/svg><\/div><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-title-wrap\"><h4 class=\"uagb-ifb-title\">PARA SIEMPRE<\/h4><\/div><p class=\"uagb-ifb-desc\">\u00bfQue no puedes verlo ahora? No te preocupes, no caduca, tienes todo el tiempo del mundo.<\/p><\/div><\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-4 wp-block-columns-is-layout-flex\" style=\"padding-top:20px;padding-bottom:20px\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<div class=\"wp-block-uagb-info-box uagb-block-654d8830 uagb-infobox__content-wrap  uagb-infobox-icon-left uagb-infobox-left uagb-infobox-stacked-tablet uagb-infobox-image-valign-top\"><div class=\"uagb-ifb-icon-wrap\"><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\"><path d=\"M256 0C114.6 0 0 114.6 0 256s114.6 256 256 256s256-114.6 256-256S397.4 0 256 0zM256 128c17.67 0 32 14.33 32 32c0 17.67-14.33 32-32 32S224 177.7 224 160C224 142.3 238.3 128 256 128zM296 384h-80C202.8 384 192 373.3 192 360s10.75-24 24-24h16v-64H224c-13.25 0-24-10.75-24-24S210.8 224 224 224h32c13.25 0 24 10.75 24 24v88h16c13.25 0 24 10.75 24 24S309.3 384 296 384z\"><\/path><\/svg><\/div><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-title-wrap\"><h4 class=\"uagb-ifb-title\">\u00bfDUDAS? NO PROBLEM&#8230;<\/h4><\/div><p class=\"uagb-ifb-desc\">\u00bfA\u00fan tienes dudas despu\u00e9s de verlo? No hay problema, puedes preguntar y te responder\u00e9 personalmente.<\/p><\/div><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<div class=\"wp-block-uagb-info-box uagb-block-b7fd8c1d uagb-infobox__content-wrap  uagb-infobox-icon-left uagb-infobox-left uagb-infobox-stacked-tablet uagb-infobox-image-valign-top\"><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-title-wrap\"><\/div><\/div><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<div class=\"wp-block-uagb-info-box uagb-block-6dbcfcd2 uagb-infobox__content-wrap  uagb-infobox-icon-left uagb-infobox-left uagb-infobox-stacked-tablet uagb-infobox-image-valign-top\"><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-title-wrap\"><\/div><\/div><\/div>\n<\/div>\n<\/div>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity is-style-dots\" style=\"margin-top:var(--wp--preset--spacing--60);margin-bottom:var(--wp--preset--spacing--60)\"\/>\n\n\n\n<h2 class=\"wp-block-heading has-text-align-center\" style=\"font-size:28px\">\u00bfQUE MODELOS SON COMPATIBLES?<\/h2>\n\n\n\n<p>Esencialmente, todas las SONY Alpha desde la a7 IV en adelante (presentada en 2020). Si tienes un modelo anterior (los que incorporan el viejo sistema de men\u00fas) entonces te interesa el <a href=\"https:\/\/hugorodriguez.com\/escuela\/cursos\/master-camera-course-sony-pre-2020-edition\/\"><em>otro SONY Master Camera Course Pre-2020<\/em><\/a>.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>a7 IV, a7 V<\/li>\n\n\n\n<li>a7R V<\/li>\n\n\n\n<li>a7S III<\/li>\n\n\n\n<li>a1, a1 II<\/li>\n\n\n\n<li>a7 CII, a7 CR<\/li>\n\n\n\n<li>a6700<\/li>\n<\/ul>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity is-style-dots\" style=\"margin-top:var(--wp--preset--spacing--60);margin-bottom:var(--wp--preset--spacing--60)\"\/>\n\n\n\n<h2 class=\"wp-block-heading has-text-align-center\" style=\"font-size:28px\">\u00bfQUE NOS DIFERENCIA DEL RESTO?<\/h2>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-5 wp-block-columns-is-layout-flex\" style=\"padding-top:20px;padding-bottom:20px\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<div class=\"wp-block-uagb-info-box uagb-block-852574e1 uagb-infobox__content-wrap  uagb-infobox-icon-left uagb-infobox-left uagb-infobox-stacked-tablet uagb-infobox-image-valign-top\"><div class=\"uagb-ifb-icon-wrap\"><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\"><path d=\"M194.6 32H317.4C338.1 32 356.4 45.22 362.9 64.82L373.3 96H448C483.3 96 512 124.7 512 160V416C512 451.3 483.3 480 448 480H64C28.65 480 0 451.3 0 416V160C0 124.7 28.65 96 64 96H138.7L149.1 64.82C155.6 45.22 173.9 32 194.6 32H194.6zM256 384C309 384 352 341 352 288C352 234.1 309 192 256 192C202.1 192 160 234.1 160 288C160 341 202.1 384 256 384z\"><\/path><\/svg><\/div><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-title-wrap\"><h4 class=\"uagb-ifb-title\">FLUJO FOTOGR\u00c1FICO<\/h4><\/div><p class=\"uagb-ifb-desc\">Un buen curso no es el que simplemente te explica los men\u00fas de izquierda a derecha y arriba a abajo (eso no tiene ning\u00fan sentido); sino el que sigue los pasos que realmente necesita una foto: enfoque, encuadre, exposici\u00f3n, revisi\u00f3n&#8230;<\/p><\/div><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<div class=\"wp-block-uagb-info-box uagb-block-2d3c60e5 uagb-infobox__content-wrap  uagb-infobox-icon-left uagb-infobox-left uagb-infobox-stacked-mobile uagb-infobox-image-valign-top\"><div class=\"uagb-ifb-icon-wrap\"><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\"><path d=\"M503.2 393.8L280.1 44.25c-10.42-16.33-37.73-16.33-48.15 0L8.807 393.8c-11.11 17.41-11.75 39.42-1.666 57.45C17.07 468.1 35.92 480 56.31 480h399.4c20.39 0 39.24-11.03 49.18-28.77C514.9 433.2 514.3 411.2 503.2 393.8zM256 111.8L327.8 224H256L208 288L177.2 235.3L256 111.8z\"><\/path><\/svg><\/div><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-title-wrap\"><h4 class=\"uagb-ifb-title\">EJEMPLOS DE TODO<\/h4><\/div><p class=\"uagb-ifb-desc\">Ver\u00e1s con tus propios ojos como se configura ese men\u00fa o qu\u00e9 efecto tiene esa funci\u00f3n en situaciones reales. No mas simples explicaciones verbales y aburridas presentaciones!<\/p><\/div><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<div class=\"wp-block-uagb-info-box uagb-block-a5ab43f8 uagb-infobox__content-wrap  uagb-infobox-icon-left uagb-infobox-left uagb-infobox-stacked-mobile uagb-infobox-image-valign-top\"><div class=\"uagb-ifb-icon-wrap\"><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\"><path d=\"M45.63 79.75L52 81.25v58.5C45 143.9 40 151.3 40 160c0 8.375 4.625 15.38 11.12 19.75L35.5 242C33.75 248.9 37.63 256 43.13 256h41.75c5.5 0 9.375-7.125 7.625-13.1L76.88 179.8C83.38 175.4 88 168.4 88 160c0-8.75-5-16.12-12-20.25V87.13L128 99.63l.001 60.37c0 70.75 57.25 128 128 128s127.1-57.25 127.1-128L384 99.62l82.25-19.87c18.25-4.375 18.25-27 0-31.5l-190.4-46c-13-3-26.62-3-39.63 0l-190.6 46C27.5 52.63 27.5 75.38 45.63 79.75zM359.2 312.8l-103.2 103.2l-103.2-103.2c-69.93 22.3-120.8 87.2-120.8 164.5C32 496.5 47.53 512 66.67 512h378.7C464.5 512 480 496.5 480 477.3C480 400 429.1 335.1 359.2 312.8z\"><\/path><\/svg><\/div><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-title-wrap\"><h4 class=\"uagb-ifb-title\">ALTA CALIDAD DOCENTE<\/h4><\/div><p class=\"uagb-ifb-desc\">&#8220;<em>Saber no es lo mismo que saber ense\u00f1ar<\/em>&#8220;. Hugo es profesor de fotograf\u00eda desde 1998 e imparte talleres y m\u00e1sters en las mejores escuelas de fotograf\u00eda y universidades del pais. Por algo ser\u00e1\u2026<\/p><\/div><\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-6 wp-block-columns-is-layout-flex\" style=\"padding-top:20px;padding-bottom:20px\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<div class=\"wp-block-uagb-info-box uagb-block-7681798d uagb-infobox__content-wrap  uagb-infobox-icon-left uagb-infobox-left uagb-infobox-stacked-tablet uagb-infobox-image-valign-top\"><div class=\"uagb-ifb-icon-wrap\"><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 576 512\"><path d=\"M279.6 160.4C282.4 160.1 285.2 160 288 160C341 160 384 202.1 384 256C384 309 341 352 288 352C234.1 352 192 309 192 256C192 253.2 192.1 250.4 192.4 247.6C201.7 252.1 212.5 256 224 256C259.3 256 288 227.3 288 192C288 180.5 284.1 169.7 279.6 160.4zM480.6 112.6C527.4 156 558.7 207.1 573.5 243.7C576.8 251.6 576.8 260.4 573.5 268.3C558.7 304 527.4 355.1 480.6 399.4C433.5 443.2 368.8 480 288 480C207.2 480 142.5 443.2 95.42 399.4C48.62 355.1 17.34 304 2.461 268.3C-.8205 260.4-.8205 251.6 2.461 243.7C17.34 207.1 48.62 156 95.42 112.6C142.5 68.84 207.2 32 288 32C368.8 32 433.5 68.84 480.6 112.6V112.6zM288 112C208.5 112 144 176.5 144 256C144 335.5 208.5 400 288 400C367.5 400 432 335.5 432 256C432 176.5 367.5 112 288 112z\"><\/path><\/svg><\/div><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-title-wrap\"><h4 class=\"uagb-ifb-title\">CONTACTO VISUAL<\/h4><\/div><p class=\"uagb-ifb-desc\">Otros cursos se limitan a mostrarte una presentaci\u00f3n con el profesor en modo &#8220;voz en off&#8221;; aqui me ver\u00e1s constantemente y las explicaciones de c\u00e1mara son con c\u00e1mara en mano, sin presentaciones.<\/p><\/div><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<div class=\"wp-block-uagb-info-box uagb-block-4c7f47de uagb-infobox__content-wrap  uagb-infobox-icon-left uagb-infobox-left uagb-infobox-stacked-mobile uagb-infobox-image-valign-top\"><div class=\"uagb-ifb-icon-wrap\"><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 384 512\"><path d=\"M384 48V512l-192-112L0 512V48C0 21.5 21.5 0 48 0h288C362.5 0 384 21.5 384 48z\"><\/path><\/svg><\/div><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-title-wrap\"><h4 class=\"uagb-ifb-title\">GARANT\u00cdA DE CALIDAD<\/h4><\/div><p class=\"uagb-ifb-desc\">La calidad de los contenidos est\u00e1 garantizada. Hugo es uno de los m\u00e1s reconocidos expertos en revelado RAW. Los contenidos y materiales del curso han sido cuidadosamente escogidos y elaborados.<\/p><\/div><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><\/div>\n<\/div>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity is-style-dots\" style=\"margin-top:var(--wp--preset--spacing--60);margin-bottom:var(--wp--preset--spacing--60)\"\/>\n\n\n\n<div class=\"wp-block-uagb-info-box uagb-block-aad6a054 uagb-infobox__content-wrap  uagb-infobox-icon-above-title uagb-infobox-image-valign-top\" id=\"certificado-hugo\"><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-image-content\"><img decoding=\"async\" src=\"https:\/\/hugorodriguez.com\/escuela\/wp-content\/uploads\/2024\/05\/Hugo-con-su-certificado-16-800px.webp\" alt=\"\" width=\"\" height=\"0\" loading=\"lazy\"\/><\/div><div class=\"uagb-ifb-title-wrap\"><h3 class=\"uagb-ifb-title\">CERTIFICADO DE FINALIZACI\u00d3N IMPRIMIBLE<\/h3><\/div><p class=\"uagb-ifb-desc\">Al terminar el curso recibir\u00e1s un certificado personalizado con tu nombre.<br>Podr\u00e1s imprimirlo a tama\u00f1o DIN A4 con alta calidad.<\/p><\/div><\/div>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity is-style-dots\" style=\"margin-top:var(--wp--preset--spacing--60);margin-bottom:var(--wp--preset--spacing--60)\"\/>\n\n\n\n<h2 class=\"wp-block-heading has-text-align-center\" id=\"programa\" style=\"font-size:28px\">PROGRAMA (8.5 h)<\/h2>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-7 wp-block-columns-is-layout-flex\" style=\"padding-top:var(--wp--preset--spacing--20);padding-bottom:var(--wp--preset--spacing--20)\">\n<div class=\"wp-block-column is-layout-flow wp-container-core-column-is-layout-19 wp-block-column-is-layout-flow\" style=\"padding-top:0;padding-bottom:0\">\n<p class=\"has-text-align-center\" style=\"margin-top:var(--wp--preset--spacing--30);margin-bottom:var(--wp--preset--spacing--30)\">I: LA C\u00c1MARA<\/p>\n\n\n\n<ul style=\"margin-top:var(--wp--preset--spacing--20);margin-bottom:var(--wp--preset--spacing--20)\" class=\"wp-block-list\">\n<li>Formaci\u00f3n de la imagen (experimento).<\/li>\n\n\n\n<li> Como NO disparar. Ajuste dioptrico (lo est\u00e1s haciendo mal).<\/li>\n<\/ul>\n\n\n\n<p class=\"has-text-align-center\" style=\"margin-top:var(--wp--preset--spacing--30);margin-bottom:var(--wp--preset--spacing--30)\">II: MANEJO GENERAL DE C\u00c1MARA<\/p>\n\n\n\n<ul style=\"margin-top:var(--wp--preset--spacing--20);margin-bottom:var(--wp--preset--spacing--20)\" class=\"wp-block-list\">\n<li>Las 4 pantallas principales. El Live View.<\/li>\n\n\n\n<li>El modo Quick men\u00fa.<\/li>\n\n\n\n<li>Configuracion base de camara.<\/li>\n\n\n\n<li>\u00bfQu\u00e9 funciones son realmente importantes?<\/li>\n<\/ul>\n\n\n\n<p class=\"has-text-align-center\" style=\"margin-top:var(--wp--preset--spacing--30);margin-bottom:var(--wp--preset--spacing--30)\">III: ENCUADRANDO<\/p>\n\n\n\n<ul style=\"margin-top:var(--wp--preset--spacing--20);margin-bottom:var(--wp--preset--spacing--20)\" class=\"wp-block-list\">\n<li>Ajustar FPS visor. Brillo visor y monitor. <\/li>\n\n\n\n<li>Nivel y cuadr\u00edcula.<\/li>\n\n\n\n<li>El Crop Factor. Focales equivalentes en APS-C y Micro 4\/3.<\/li>\n\n\n\n<li>Adaptadores de \u00f3pticas. Speedboosters.<\/li>\n<\/ul>\n\n\n\n<p class=\"has-text-align-center\" style=\"margin-top:var(--wp--preset--spacing--20);margin-bottom:var(--wp--preset--spacing--20)\">IV: ENFOCANDO<\/p>\n\n\n\n<ul style=\"margin-top:var(--wp--preset--spacing--20);margin-bottom:var(--wp--preset--spacing--20)\" class=\"wp-block-list\">\n<li>Tipos de AF.<\/li>\n\n\n\n<li>Areas AF.<\/li>\n\n\n\n<li>Tracking. Reconocimiento de personas, sujetos y vehiculos.<\/li>\n\n\n\n<li>Prioridad al AF\/disparo. Disociar AF-ON<\/li>\n\n\n\n<li>AF + MF. Asistencia al enfoque M. Focus peaking.<\/li>\n\n\n\n<li>El estabilizador \u00f3ptico. Sweet spot.<\/li>\n\n\n\n<li>Boton PdC. Escala de la PdC en \u00f3pticas\/Live View.<\/li>\n\n\n\n<li>Dual Zoom.<\/li>\n<\/ul>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<p class=\"has-text-align-center\" style=\"margin-top:var(--wp--preset--spacing--30);margin-bottom:var(--wp--preset--spacing--30)\">V: EL WHITE BALANCE<\/p>\n\n\n\n<ul style=\"margin-top:var(--wp--preset--spacing--20);margin-bottom:var(--wp--preset--spacing--20)\" class=\"wp-block-list\">\n<li>Funcionamiento del WB. Los modos.<\/li>\n\n\n\n<li>WB Custom. Lectura con carta. C\u00f3mo lo hago yo.<\/li>\n<\/ul>\n\n\n\n<p class=\"has-text-align-center\" style=\"margin-top:var(--wp--preset--spacing--30);margin-bottom:var(--wp--preset--spacing--30)\">VI: MIDIENDO LA EXPOSICI\u00d3N<\/p>\n\n\n\n<ul style=\"margin-top:var(--wp--preset--spacing--20);margin-bottom:var(--wp--preset--spacing--20)\" class=\"wp-block-list\">\n<li>ISO nativo e ISOs Low.<\/li>\n\n\n\n<li>El ISO Autom\u00e1tico \u00bfin\u00fatil?<\/li>\n\n\n\n<li>Invarianza ISO, la clave.<\/li>\n\n\n\n<li>Dual ISO <sup>NEW<\/sup><\/li>\n\n\n\n<li>Compensaci\u00f3n exposici\u00f3n r\u00e1pida<\/li>\n\n\n\n<li>Medici\u00f3n e histogramas.<\/li>\n\n\n\n<li>Clipping en altas luces.<\/li>\n\n\n\n<li>Estilos: no obtendras mejor color.<\/li>\n\n\n\n<li>Simulaci\u00f3n de exp. \/ OVF.<\/li>\n\n\n\n<li>Estilos e histograma en JPG\/RAW. Estilos planos.<\/li>\n<\/ul>\n\n\n\n<p class=\"has-text-align-center\" style=\"margin-top:var(--wp--preset--spacing--30);margin-bottom:var(--wp--preset--spacing--30)\">VII: LA CAPTURA<\/p>\n\n\n\n<ul style=\"margin-top:var(--wp--preset--spacing--20);margin-bottom:var(--wp--preset--spacing--20)\" class=\"wp-block-list\">\n<li>RAW 14 bits. sRAW y mRAW. RAW comprimido.<\/li>\n\n\n\n<li>Disparo con e-shutter? Rolling y global shutter.<\/li>\n\n\n\n<li>Opciones de disparo.<\/li>\n\n\n\n<li>El estabilizador y la trepidaci\u00f3n.<\/li>\n\n\n\n<li>Optimizando la captura al m\u00e1ximo.<\/li>\n<\/ul>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<p class=\"has-text-align-center\" style=\"margin-top:var(--wp--preset--spacing--30);margin-bottom:var(--wp--preset--spacing--30)\">VIII: REVISANDO<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Revision a su tiempo. Ampliar realmente al 100%. Atajo r\u00e1pido.<\/li>\n\n\n\n<li>Enfoque de precisi\u00f3n. RR Baja.<\/li>\n\n\n\n<li>Histograma en Play. Histogramas RGB. Clipping en RGB.<\/li>\n<\/ul>\n\n\n\n<p class=\"has-text-align-center\" style=\"margin-top:var(--wp--preset--spacing--30);margin-bottom:var(--wp--preset--spacing--30)\">IX: FOTO COMPUTACIONAL<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Disparo HighRes<\/li>\n\n\n\n<li>Focus Stacking<\/li>\n<\/ul>\n\n\n\n<p class=\"has-text-align-center\" style=\"margin-top:var(--wp--preset--spacing--30);margin-bottom:var(--wp--preset--spacing--30)\">X: VIDEO<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Resoluciones y codecs. Para ver y para editar.<\/li>\n\n\n\n<li>Framerates. \u00bfPAL? No, gracias. Recomendaciones.<\/li>\n\n\n\n<li>La compresion en video<\/li>\n\n\n\n<li>Codecs y containers<\/li>\n\n\n\n<li>Motion Blur<\/li>\n<\/ul>\n\n\n\n<p class=\"has-text-align-center\" style=\"margin-top:var(--wp--preset--spacing--30);margin-bottom:var(--wp--preset--spacing--30)\">XI: MANEJO DESDE LA APP<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Control, modificar parametros y disparar la camara.<\/li>\n\n\n\n<li>Ver y descargar fotos de la camara<\/li>\n<\/ul>\n\n\n\n<p class=\"has-text-align-center\" style=\"margin-top:var(--wp--preset--spacing--30);margin-bottom:var(--wp--preset--spacing--30)\">XII: PERSONALIZANDO LA C\u00c1MARA<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Funciones para mejorar la seguridad.<\/li>\n\n\n\n<li>Otras funciones utiles.<\/li>\n\n\n\n<li>My Menu. Personalizar botones.<\/li>\n\n\n\n<li>Los modos Custom C1, C2\u2026<\/li>\n\n\n\n<li>Guardar configuraci\u00f3n de la c\u00e1mara. Descargas.<\/li>\n\n\n\n<li>Actualizar el firmware <sup>EN BREVE<\/sup><\/li>\n<\/ul>\n<\/div>\n<\/div>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity is-style-dots\"\/>\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading has-text-align-center\" style=\"font-size:28px\">PACKS<\/h2>\n\n\n\n<p>Compra un pack y ahorra<\/p>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-11 wp-block-columns-is-layout-flex\" style=\"padding-top:var(--wp--preset--spacing--50);padding-bottom:var(--wp--preset--spacing--50)\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:33%\" id=\"pack-viajes-sony\">\n<h2 class=\"wp-block-heading has-medium-font-size\"><a href=\"https:\/\/hugorodriguez.com\/escuela\/curso-fotografia\/pack-fotografia-de-viajes-sony-master-camera-course-post-2020\/\">FOTOGRAF\u00cdA DE VIAJES + SONY MASTER COURSE<\/a><\/h2>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/hugorodriguez.com\/escuela\/curso-fotografia\/pack-fotografia-de-viajes-sony-master-camera-course-post-2020\/\"><img loading=\"lazy\" decoding=\"async\" width=\"696\" height=\"469\" src=\"https:\/\/hugorodriguez.com\/escuela\/wp-content\/uploads\/2025\/12\/Pack-Luminar-NEO-Fondo-SONY-Post2020.webp\" alt=\"\" class=\"wp-image-11060\" srcset=\"https:\/\/hugorodriguez.com\/escuela\/wp-content\/uploads\/2025\/12\/Pack-Luminar-NEO-Fondo-SONY-Post2020.webp 696w, https:\/\/hugorodriguez.com\/escuela\/wp-content\/uploads\/2025\/12\/Pack-Luminar-NEO-Fondo-SONY-Post2020-600x404.webp 600w, https:\/\/hugorodriguez.com\/escuela\/wp-content\/uploads\/2025\/12\/Pack-Luminar-NEO-Fondo-SONY-Post2020-300x202.webp 300w\" sizes=\"auto, (max-width: 696px) 100vw, 696px\" \/><\/a><\/figure>\n\n\n\n<div class=\"wp-block-columns is-not-stacked-on-mobile is-layout-flex wp-container-core-columns-is-layout-8 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:75%\">\n<p>Domina el manejo de tu c\u00e1mara SONY y aprende a tomar fotos impactantes en tus viajes con Tino Soriano.<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:25%\">\n<h2 class=\"wp-block-heading has-text-align-right has-cyan-bluish-gray-color has-text-color has-link-color has-medium-font-size wp-elements-e4a2e84f6389c848374d852a129e11d3\"><s>134,95\u20ac<\/s><br><br>59,95\u20ac<\/h2>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:33%\" id=\"pack-viajes-olympus-om\">\n<h2 class=\"wp-block-heading has-medium-font-size\"><a href=\"https:\/\/hugorodriguez.com\/escuela\/curso-fotografia\/pack-luminar-neo-a-fondo-2025-sony-master-camera-course-post-2020-edition\/\">LUMINAR NEO A FONDO + SONY MASTER COURSE<\/a><\/h2>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/hugorodriguez.com\/escuela\/curso-fotografia\/pack-luminar-neo-a-fondo-2025-sony-master-camera-course-post-2020-edition\/\"><img loading=\"lazy\" decoding=\"async\" width=\"660\" height=\"454\" src=\"https:\/\/hugorodriguez.com\/escuela\/wp-content\/uploads\/2025\/12\/Pack-Luminar-NEO-Fondo-SONY-II-660px.webp\" alt=\"\" class=\"wp-image-11305\" srcset=\"https:\/\/hugorodriguez.com\/escuela\/wp-content\/uploads\/2025\/12\/Pack-Luminar-NEO-Fondo-SONY-II-660px.webp 660w, https:\/\/hugorodriguez.com\/escuela\/wp-content\/uploads\/2025\/12\/Pack-Luminar-NEO-Fondo-SONY-II-660px-600x413.webp 600w, https:\/\/hugorodriguez.com\/escuela\/wp-content\/uploads\/2025\/12\/Pack-Luminar-NEO-Fondo-SONY-II-660px-300x206.webp 300w\" sizes=\"auto, (max-width: 660px) 100vw, 660px\" \/><\/a><\/figure>\n\n\n\n<div class=\"wp-block-columns is-not-stacked-on-mobile is-layout-flex wp-container-core-columns-is-layout-9 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:75%\">\n<p>Domina el manejo de tu c\u00e1mara SONY y aprende a retocar tus fotos con el programa de moda: Luminar NEO.<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:25%\">\n<h2 class=\"wp-block-heading has-text-align-right has-cyan-bluish-gray-color has-text-color has-link-color has-medium-font-size wp-elements-6a0a6f313ea14eb5c6804b6e5f885714\"><s>154,90<\/s>\u20ac<br><br>64,95\u20ac<\/h2>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:33%\" id=\"pack-viajes-canon\">\n<h2 class=\"wp-block-heading has-medium-font-size\"><a href=\"https:\/\/hugorodriguez.com\/escuela\/curso-fotografia\/pack-calibrar-monitor-i1-display-sony-master-camera-course\/\">CALIBRAR EL MONITOR CON i1 DISPLAY + SONY MASTER<\/a><\/h2>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/hugorodriguez.com\/escuela\/curso-fotografia\/pack-calibrar-monitor-i1-display-sony-master-camera-course\/\"><img loading=\"lazy\" decoding=\"async\" width=\"660\" height=\"454\" src=\"https:\/\/hugorodriguez.com\/escuela\/wp-content\/uploads\/2026\/01\/Pack-CalMon-i1Display-SONY-Master-660px.webp\" alt=\"\" class=\"wp-image-11589\" srcset=\"https:\/\/hugorodriguez.com\/escuela\/wp-content\/uploads\/2026\/01\/Pack-CalMon-i1Display-SONY-Master-660px.webp 660w, https:\/\/hugorodriguez.com\/escuela\/wp-content\/uploads\/2026\/01\/Pack-CalMon-i1Display-SONY-Master-660px-300x206.webp 300w, https:\/\/hugorodriguez.com\/escuela\/wp-content\/uploads\/2026\/01\/Pack-CalMon-i1Display-SONY-Master-660px-600x413.webp 600w\" sizes=\"auto, (max-width: 660px) 100vw, 660px\" \/><\/a><\/figure>\n\n\n\n<div class=\"wp-block-columns is-not-stacked-on-mobile is-layout-flex wp-container-core-columns-is-layout-10 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:75%\">\n<p>Domina tu c\u00e1mara SONY y aprende a calibrar tu monitor con el i1 Display.<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:25%\">\n<h2 class=\"wp-block-heading has-text-align-right has-cyan-bluish-gray-color has-text-color has-link-color has-medium-font-size wp-elements-2ff4462fed0994995e0684c371febc3b\"><s>114,95<\/s>\u20ac<br><br>54,95\u20ac<\/h2>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-buttons is-content-justification-center is-layout-flex wp-container-core-buttons-is-layout-2 wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/hugorodriguez.com\/escuela\/categoria-producto\/packs\/\">VER TODOS LOS PACKS<\/a><\/div>\n<\/div>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity is-style-dots\"\/>\n\n\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading has-text-align-center\" id=\"tarjeta-regalo\" style=\"font-size:28px\">\u00bfQuieres regalar el curso?<\/h2>\n\n\n\n<p>\u00bfquieres regalar este curso a un ser querido? Ahora tambi\u00e9n puedes con la tarjeta de regalo. Simplemente elige la cantidad, introduce los datos de esa persona y los tuyos&#8230; y listo!<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full\"><a href=\"https:\/\/hugorodriguez.com\/escuela\/curso-fotografia\/tarjeta-regalo\/\"><img loading=\"lazy\" decoding=\"async\" width=\"660\" height=\"440\" src=\"https:\/\/hugorodriguez.com\/escuela\/wp-content\/uploads\/2025\/12\/tarjeta-regalo-hr.webp\" alt=\"\" class=\"wp-image-11487\" srcset=\"https:\/\/hugorodriguez.com\/escuela\/wp-content\/uploads\/2025\/12\/tarjeta-regalo-hr.webp 660w, https:\/\/hugorodriguez.com\/escuela\/wp-content\/uploads\/2025\/12\/tarjeta-regalo-hr-300x200.webp 300w, https:\/\/hugorodriguez.com\/escuela\/wp-content\/uploads\/2025\/12\/tarjeta-regalo-hr-600x400.webp 600w\" sizes=\"auto, (max-width: 660px) 100vw, 660px\" \/><\/a><\/figure>\n\n\n\n<div class=\"wp-block-buttons is-content-justification-center is-layout-flex wp-container-core-buttons-is-layout-3 wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/hugorodriguez.com\/escuela\/curso-fotografia\/tarjeta-regalo\/\">VER LAS TARJETAS DE REGALO<\/a><\/div>\n<\/div>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity is-style-dots\" style=\"margin-top:var(--wp--preset--spacing--60);margin-bottom:var(--wp--preset--spacing--60)\"\/>\n\n\n\n<h2 class=\"wp-block-heading has-text-align-center\" style=\"font-size:28px\">SOBRE HUGO RODR\u00cdGUEZ<\/h2>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-12 wp-block-columns-is-layout-flex\" style=\"padding-top:var(--wp--preset--spacing--30);padding-bottom:var(--wp--preset--spacing--30)\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:12%\">\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"197\" height=\"250\" src=\"https:\/\/hugorodriguez.com\/escuela\/wp-content\/uploads\/2024\/02\/HRA3768-250px.jpg\" alt=\"\" class=\"wp-image-4504\"\/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<p>Estudi\u00f3 Ingenier\u00eda T\u00e9cnica Industrial y fotograf\u00eda en el <strong>IEFC<\/strong>. Trabaja de profesor de t\u00e9cnica fotogr\u00e1fica, y se ha especializado en gesti\u00f3n del color, captura digital y revelado de RAW, habiendo impartido multitud de cursos, m\u00e1sters y conferencias desde 1999 en escuelas como el <strong>IEFC<\/strong>, <strong>EFTI<\/strong>, <strong>Elisava <\/strong>o la <strong>ESCAC<\/strong>, y en universidades como la <strong>Universidad de Barcelona<\/strong>, la <strong>Complutense <\/strong>o <strong>La Salle<\/strong>.<br><br>Tambi\u00e9n trabaja de t\u00e9cnico del color para el laboratorio fotogr\u00e1fico <strong>EGM<\/strong>. Ofrece sus servicios en <a href=\"http:\/\/www.perfilesdecolor.com\/\">perfilesdecolor.com<\/a>. Ha desarrollado y fabrica las cartas de color <a href=\"https:\/\/www.hugorodriguez.com\/blog\/hr-1-superchroma-esp\/\"><strong>HR-1 SuperChroma<\/strong><\/a> e <strong>IT8<\/strong>.<\/p>\n\n\n\n<p>Ha <strong>publicado docenas de reviews de c\u00e1maras<\/strong> de todos los tipos, tama\u00f1os y categor\u00edas para la -ya extinta-<strong> revista Casanova Professional<\/strong>, una revista orientada exclusivamente a profesionales.<br><br>Entre sus clientes se encuentran marcas como <strong>ZARA Home<\/strong>, <strong>MANGO<\/strong>, <strong>Desigual<\/strong>, <strong>PULL&amp;BEAR<\/strong>, <strong>OYSHO<\/strong>, <strong>Massimo Dutti<\/strong>, <strong>Pedro del Hierro<\/strong>, a los que les realiza la gesti\u00f3n del color, e instituciones como el <strong>Museo del Prado<\/strong>, la <strong>Biblioteca Nacional<\/strong> o el <strong>MACBA<\/strong>, a los que les asesora sobre gesti\u00f3n del color.<br><br>Se ha encargado de la gesti\u00f3n de color en la pel\u00edcula <a href=\"https:\/\/www.netflix.com\/es\/title\/80183187\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Klaus<\/strong><\/a>, nominada a mejor pel\u00edcula de animaci\u00f3n en los <strong>Oscar 2020<\/strong>.<br><br>Ha escrito y publicado <strong>5 libros<\/strong>, incluyendo <a href=\"http:\/\/www.hugorodriguez.com\/blog\/coleccion-bitpixel\/captura-digital-y-revelado-de-raw-2a-edicion\/\"><strong>Captura digital y revelado de RAW<\/strong><\/a>, un \u00e9xito de ventas (m\u00e1s de 20.000 ejemplares vendidos).<br><br>Es colaborador de varias firmas, como <strong>Skylum<\/strong>, <strong>Phase One<\/strong>, <strong>Adobe<\/strong>, <strong>BenQ <\/strong>o <strong>BasICColor<\/strong>. Es o ha sido embajador de <strong>BenQ<\/strong> y <strong>PhaseOne<\/strong> y es <strong>Certified Professional<\/strong> por esta \u00faltima. <a href=\"https:\/\/hugorodriguez.com\/escuela\/cursos\/curso-de-c1-23-con-prisa-showroom\/\">Ha traducido al espa\u00f1ol softwares como <strong>3DLUT Creator<\/strong>, <strong>SNS-HDR<\/strong> o <strong>CoCa<\/strong>.<\/a><\/p>\n<\/div>\n<\/div>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity is-style-dots\" style=\"margin-top:var(--wp--preset--spacing--60);margin-bottom:var(--wp--preset--spacing--60)\"\/>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-a3de593a default uagb-is-root-container\">\n<div class=\"wp-block-uagb-container uagb-block-e6c2b3ed\">\n<p class=\"has-text-align-center\" style=\"font-size:24px\">Apuntate al curso por s\u00f3lo  <s>74,95\u20ac<\/s> <strong>34,95\u20ac<\/strong><\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-3f9c00d1\"><div class=\"learndash-wrapper learndash-wrap learndash-shortcode-wrap\"><a class=\"btn-join learndash-button-closed\" id=\"btn-join\" href=\"https:\/\/hugorodriguez.com\/escuela\/finalizar-compra\/?add-to-cart=11057\">Apuntarme<\/a><\/div><\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Ya llevas unos a\u00f1os con la fotograf\u00eda y tienes una SONY Alpha. Te consideras un usuario de nivel medio o avanzado, o eres un profesional. Tus fotos ya empiezan a estar muy bien, pero quieres seguir mejorando; el problema es que cuanto mayor es el nivel que tienes, m\u00e1s cuesta seguir subiendo, \u00bfverdad? Es l\u00f3gico, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":4565,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_uag_custom_page_level_css":"","site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-gradient":""}},"footnotes":""},"class_list":["post-10797","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>SONY Camera Master Course - Post-2020 - Escuela de fotograf\u00eda<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/hugorodriguez.com\/escuela\/cursos\/sony-camera-master-course-post-2020-edition\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"SONY Camera Master Course - Post-2020 - Escuela de fotograf\u00eda\" \/>\n<meta property=\"og:description\" content=\"Ya llevas unos a\u00f1os con la fotograf\u00eda y tienes una SONY Alpha. Te consideras un usuario de nivel medio o avanzado, o eres un profesional. Tus fotos ya empiezan a estar muy bien, pero quieres seguir mejorando; el problema es que cuanto mayor es el nivel que tienes, m\u00e1s cuesta seguir subiendo, \u00bfverdad? Es l\u00f3gico, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/hugorodriguez.com\/escuela\/cursos\/sony-camera-master-course-post-2020-edition\/\" \/>\n<meta property=\"og:site_name\" content=\"Escuela de fotograf\u00eda\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-03T19:42:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/hugorodriguez.com\/escuela\/wp-content\/uploads\/2025\/11\/Videocurso-Master-CAM-SONY-II-01-660px.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"960\" \/>\n\t<meta property=\"og:image:height\" content=\"540\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"14 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/hugorodriguez.com\/escuela\/cursos\/sony-camera-master-course-post-2020-edition\/\",\"url\":\"https:\/\/hugorodriguez.com\/escuela\/cursos\/sony-camera-master-course-post-2020-edition\/\",\"name\":\"SONY Camera Master Course - Post-2020 - Escuela de fotograf\u00eda\",\"isPartOf\":{\"@id\":\"https:\/\/hugorodriguez.com\/escuela\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/hugorodriguez.com\/escuela\/cursos\/sony-camera-master-course-post-2020-edition\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/hugorodriguez.com\/escuela\/cursos\/sony-camera-master-course-post-2020-edition\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/hugorodriguez.com\/escuela\/wp-content\/uploads\/2025\/11\/Videocurso-Master-CAM-SONY-II-01-660px.webp\",\"datePublished\":\"2025-11-27T22:03:51+00:00\",\"dateModified\":\"2026-01-03T19:42:46+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/hugorodriguez.com\/escuela\/cursos\/sony-camera-master-course-post-2020-edition\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/hugorodriguez.com\/escuela\/cursos\/sony-camera-master-course-post-2020-edition\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/hugorodriguez.com\/escuela\/cursos\/sony-camera-master-course-post-2020-edition\/#primaryimage\",\"url\":\"https:\/\/hugorodriguez.com\/escuela\/wp-content\/uploads\/2025\/11\/Videocurso-Master-CAM-SONY-II-01-660px.webp\",\"contentUrl\":\"https:\/\/hugorodriguez.com\/escuela\/wp-content\/uploads\/2025\/11\/Videocurso-Master-CAM-SONY-II-01-660px.webp\",\"width\":960,\"height\":540},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/hugorodriguez.com\/escuela\/cursos\/sony-camera-master-course-post-2020-edition\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/hugorodriguez.com\/escuela\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cursos\",\"item\":\"https:\/\/hugorodriguez.com\/escuela\/cursos\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"SONY Camera Master Course &#8211; Post-2020\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/hugorodriguez.com\/escuela\/#website\",\"url\":\"https:\/\/hugorodriguez.com\/escuela\/\",\"name\":\"Escuela de fotograf\u00eda\",\"description\":\"Escuela online de fotografia de Hugo Rodriguez\",\"publisher\":{\"@id\":\"https:\/\/hugorodriguez.com\/escuela\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/hugorodriguez.com\/escuela\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/hugorodriguez.com\/escuela\/#organization\",\"name\":\"Escuela de fotograf\u00eda\",\"url\":\"https:\/\/hugorodriguez.com\/escuela\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/hugorodriguez.com\/escuela\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/hugorodriguez.com\/escuela\/wp-content\/uploads\/2023\/11\/cropped-Loho-hugorodriguez-escuela.webp\",\"contentUrl\":\"https:\/\/hugorodriguez.com\/escuela\/wp-content\/uploads\/2023\/11\/cropped-Loho-hugorodriguez-escuela.webp\",\"width\":671,\"height\":201,\"caption\":\"Escuela de fotograf\u00eda\"},\"image\":{\"@id\":\"https:\/\/hugorodriguez.com\/escuela\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"SONY Camera Master Course - Post-2020 - Escuela de fotograf\u00eda","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/hugorodriguez.com\/escuela\/cursos\/sony-camera-master-course-post-2020-edition\/","og_locale":"es_ES","og_type":"article","og_title":"SONY Camera Master Course - Post-2020 - Escuela de fotograf\u00eda","og_description":"Ya llevas unos a\u00f1os con la fotograf\u00eda y tienes una SONY Alpha. Te consideras un usuario de nivel medio o avanzado, o eres un profesional. Tus fotos ya empiezan a estar muy bien, pero quieres seguir mejorando; el problema es que cuanto mayor es el nivel que tienes, m\u00e1s cuesta seguir subiendo, \u00bfverdad? Es l\u00f3gico, [&hellip;]","og_url":"https:\/\/hugorodriguez.com\/escuela\/cursos\/sony-camera-master-course-post-2020-edition\/","og_site_name":"Escuela de fotograf\u00eda","article_modified_time":"2026-01-03T19:42:46+00:00","og_image":[{"width":960,"height":540,"url":"https:\/\/hugorodriguez.com\/escuela\/wp-content\/uploads\/2025\/11\/Videocurso-Master-CAM-SONY-II-01-660px.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"14 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/hugorodriguez.com\/escuela\/cursos\/sony-camera-master-course-post-2020-edition\/","url":"https:\/\/hugorodriguez.com\/escuela\/cursos\/sony-camera-master-course-post-2020-edition\/","name":"SONY Camera Master Course - Post-2020 - Escuela de fotograf\u00eda","isPartOf":{"@id":"https:\/\/hugorodriguez.com\/escuela\/#website"},"primaryImageOfPage":{"@id":"https:\/\/hugorodriguez.com\/escuela\/cursos\/sony-camera-master-course-post-2020-edition\/#primaryimage"},"image":{"@id":"https:\/\/hugorodriguez.com\/escuela\/cursos\/sony-camera-master-course-post-2020-edition\/#primaryimage"},"thumbnailUrl":"https:\/\/hugorodriguez.com\/escuela\/wp-content\/uploads\/2025\/11\/Videocurso-Master-CAM-SONY-II-01-660px.webp","datePublished":"2025-11-27T22:03:51+00:00","dateModified":"2026-01-03T19:42:46+00:00","breadcrumb":{"@id":"https:\/\/hugorodriguez.com\/escuela\/cursos\/sony-camera-master-course-post-2020-edition\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/hugorodriguez.com\/escuela\/cursos\/sony-camera-master-course-post-2020-edition\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/hugorodriguez.com\/escuela\/cursos\/sony-camera-master-course-post-2020-edition\/#primaryimage","url":"https:\/\/hugorodriguez.com\/escuela\/wp-content\/uploads\/2025\/11\/Videocurso-Master-CAM-SONY-II-01-660px.webp","contentUrl":"https:\/\/hugorodriguez.com\/escuela\/wp-content\/uploads\/2025\/11\/Videocurso-Master-CAM-SONY-II-01-660px.webp","width":960,"height":540},{"@type":"BreadcrumbList","@id":"https:\/\/hugorodriguez.com\/escuela\/cursos\/sony-camera-master-course-post-2020-edition\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/hugorodriguez.com\/escuela\/"},{"@type":"ListItem","position":2,"name":"Cursos","item":"https:\/\/hugorodriguez.com\/escuela\/cursos\/"},{"@type":"ListItem","position":3,"name":"SONY Camera Master Course &#8211; Post-2020"}]},{"@type":"WebSite","@id":"https:\/\/hugorodriguez.com\/escuela\/#website","url":"https:\/\/hugorodriguez.com\/escuela\/","name":"Escuela de fotograf\u00eda","description":"Escuela online de fotografia de Hugo Rodriguez","publisher":{"@id":"https:\/\/hugorodriguez.com\/escuela\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/hugorodriguez.com\/escuela\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/hugorodriguez.com\/escuela\/#organization","name":"Escuela de fotograf\u00eda","url":"https:\/\/hugorodriguez.com\/escuela\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/hugorodriguez.com\/escuela\/#\/schema\/logo\/image\/","url":"https:\/\/hugorodriguez.com\/escuela\/wp-content\/uploads\/2023\/11\/cropped-Loho-hugorodriguez-escuela.webp","contentUrl":"https:\/\/hugorodriguez.com\/escuela\/wp-content\/uploads\/2023\/11\/cropped-Loho-hugorodriguez-escuela.webp","width":671,"height":201,"caption":"Escuela de fotograf\u00eda"},"image":{"@id":"https:\/\/hugorodriguez.com\/escuela\/#\/schema\/logo\/image\/"}}]}},"uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false,"woocommerce_thumbnail":false,"woocommerce_single":false,"woocommerce_gallery_thumbnail":false},"uagb_author_info":{"display_name":"Hugo Rguez","author_link":"https:\/\/hugorodriguez.com\/escuela\/author\/hurodal_escuela\/"},"uagb_comment_info":0,"uagb_excerpt":"Ya llevas unos a\u00f1os con la fotograf\u00eda y tienes una SONY Alpha. Te consideras un usuario de nivel medio o avanzado, o eres un profesional. Tus fotos ya empiezan a estar muy bien, pero quieres seguir mejorando; el problema es que cuanto mayor es el nivel que tienes, m\u00e1s cuesta seguir subiendo, \u00bfverdad? Es l\u00f3gico,&hellip;","_links":{"self":[{"href":"https:\/\/hugorodriguez.com\/escuela\/wp-json\/wp\/v2\/pages\/10797","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hugorodriguez.com\/escuela\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/hugorodriguez.com\/escuela\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/hugorodriguez.com\/escuela\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/hugorodriguez.com\/escuela\/wp-json\/wp\/v2\/comments?post=10797"}],"version-history":[{"count":19,"href":"https:\/\/hugorodriguez.com\/escuela\/wp-json\/wp\/v2\/pages\/10797\/revisions"}],"predecessor-version":[{"id":11605,"href":"https:\/\/hugorodriguez.com\/escuela\/wp-json\/wp\/v2\/pages\/10797\/revisions\/11605"}],"up":[{"embeddable":true,"href":"https:\/\/hugorodriguez.com\/escuela\/wp-json\/wp\/v2\/pages\/4565"}],"wp:attachment":[{"href":"https:\/\/hugorodriguez.com\/escuela\/wp-json\/wp\/v2\/media?parent=10797"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}